{"id":1579,"date":"2022-01-21T09:54:09","date_gmt":"2022-01-21T09:54:09","guid":{"rendered":"https:\/\/www.laqcolours.com\/politica-sui-cookie\/"},"modified":"2024-03-14T11:28:21","modified_gmt":"2024-03-14T11:28:21","slug":"politica-sui-cookie","status":"publish","type":"page","link":"https:\/\/www.laqcolours.com\/it\/politica-sui-cookie\/","title":{"rendered":"Politica sui cookie"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h1>Informativa sui cookie<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Questa politica sui cookie \u00e8 stata aggiornata l'ultima volta il Gennaio 21, 2022 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.<\/i><br><\/p><h2>1. Introduzione<\/h2><p>Il nostro sito web, <a href=\"https:\/\/www.laqcolours.com\/it\/\">https:\/\/www.laqcolours.com\/it\/<\/a> (di seguito: \"il sito web\") utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite \"cookie\"). I cookie vengono anche inseriti da terze parti che abbiamo ingaggiato. Nel documento sottostante ti informiamo sull'uso dei cookie sul nostro sito web.<\/p><h2>2. Cosa sono i cookie?<\/h2><p>I cookie sono dei semplici file spediti assieme alle pagine di questo sito e salvati dal tuo browser sul disco rigido del tuo computer o altri dispositivi. Le informazioni raccolte in essi possono venire rispediti ai nostri server oppure ai server di terze parti durante la prossima visita.<\/p><h2>3. Cosa sono gli script?<\/h2><p>Uno script \u00e8 un pezzo di codice usato per far funzionare correttamente ed interattivamente il nostro sito. Questo codice viene eseguito sui nostri server o sul tuo dispositivo.<\/p><h2>4. Cos&#039;\u00e8 un web beacon?<\/h2><p>Un web beacon (o pixel tag) \u00e8 un piccolo, invisibile pezzo di testo o immagine su un sito che viene usato per monitorare il traffico di un sito web. Per fare questo, diversi dati su di te vengono conservati utilizzando dei web beacon.<\/p><h2>5. Cookie<\/h2><p class=\"cmplz-subtitle\">5.1 Cookie tecnici o funzionali<\/p><p>Alcuni cookie assicurano il corretto funzionamento del sito e che le tue preferenze rimangano valide. Piazzando cookie funzionali, rendiamo pi\u00f9 facile per te visitare il nostro sito web. In questo modo non devi inserire ripetutamente le stesse informazioni quando visiti il nostro sito web, per esempio, l'oggetto rimane nel tuo carrello finch\u00e9 non hai pagato. Possiamo piazzare questi cookie senza il tuo consenso.<\/p><p class=\"cmplz-subtitle\">5.2 Cookie di marketing\/tracciamento<\/p><p>I cookie di marketing\/tracciamento sono cookie o qualsiasi altra forma di memorizzazione locale, utilizzati per creare profili utente per visualizzare pubblicit\u00e0 o per tracciare l'utente su questo sito web o su diversi siti web per scopi di marketing simili.<\/p><p class=\"cmplz-subtitle\">5.3 Social media<\/p><p>Sul nostro sito web abbiamo inserito contenuti di Facebook e Instagram per promuovere pagine web (ad es. \"mi piace\", \"pin\") o condividerle (ad es. \"tweet\") su social network come Facebook e Instagram. Questo contenuto \u00e8 incorporato con codice derivato da Facebook e Instagram e inserisce cookie. Questo contenuto potrebbe memorizzare ed elaborare alcune informazioni per la pubblicit\u00e0 personalizzata.<\/p><p>Leggi l'informativa sulla privacy di questi social network (che possono cambiare regolarmente) per sapere cosa fanno con i tuoi dati (personali) che processano usando questi cookie. I dati ottenuti vengono anonimizzati quanto possibile. Facebook e Instagram si trovano negli Stati Uniti.<\/p><h2>6. Cookie inseriti<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Read if cookies can be placed<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store logged in users<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Marketing\/Tracking<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing\/Tracking<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/tcb_google_fonts\/\">Google Fonts API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">expires immediately<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Read user IP address<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Facebook<\/h3>\n\t\t<p>Marketing\/Tracking, Functional<\/p>\n\t\t<label for=\"cmplz_service_facebook\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service facebook<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_facebook\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"facebook\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing\/Tracking<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/_fbc\/\">_fbc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">2 years<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store last visit<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/fbm_\/\">fbm*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store account details<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/xs\/\">xs<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">3 months<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store a unique session ID<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/fr\/\">fr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">3 months<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Provide ad delivery or retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/act\/\">act<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">90 days<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store logged in users<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/_fbp\/\">_fbp<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">3 months<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store and track visits across websites<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/datr\/\">datr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">2 years<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Provide fraud prevention<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/c_user\/\">c_user<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">30 days<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store a unique user ID<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/sb\/\">sb<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">2 years<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store browser details<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/_fbm_\/\">*_fbm_<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store account details<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wd\/\">wd<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 week<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Read screen resolution<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/csm\/\">csm<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">90 days<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Provide fraud prevention<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/actppresence\/\">actppresence<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store and track if the browser tab is active<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Varie<\/h3>\n\t\t<p>Scopo in attesa di indagine<\/p>\n\t\t<label for=\"cmplz_service_varie\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service varie<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_varie\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"varie\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>La condivisione dei dati \u00e8 in attesa di indagine<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">continueReview<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wpEmojiSettingsSupports<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-wpml_current_language<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-wpml_current_admin_language_d41d8cd98f00b204e9800998ecf8427e<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-editor-available-post-102-fb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consenttype<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-editor-available-post-1039-fb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-autosave-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-saved-post-1041-bb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-editor-available-post-178-fb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-reloaded-post-178-vb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">etfb-autosave-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-saved-post-256-fb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-saved-post-102-fb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-saved-post-1100-bb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-saved-post-1099-bb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-editor-available-post-1099-fb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-saved-post-1099-fb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">\/wp-admin\/admin.php-elfinder-lastdirwp_file_manager<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info_33323937-6566-5839-a663-376633343563<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">\/wp-admin\/admin.php-elfinder-toolbarhideswp_file_manager<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consenso<\/h2><p>Quando visiti il sito web per la prima volta, noi mostreremo un popup con una spiegazione dei cookie. Appena clicchi su \"Guardar preferencias\", dai il permesso a noi di usare le categorie di cookie e plugin come descritto in questa dichiarazione relativa ai popup e cookie. Puoi disabilitare i cookie attraverso il tuo browser, ma prendi in considerazione, che il nostro sito web potrebbe non funzionare pi\u00f9 correttamente.<\/p><p class=\"cmplz-subtitle\">7.1 Gestisci le tue impostazioni di consenso<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Hai caricato la Cookie Policy senza supporto javascript.&nbsp;Su AMP, puoi usare il pulsante di gestione del consenso in fondo alla pagina.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Abilitare\/disabilitare e cancellazione dei cookie<\/h2><p>Puoi usare il tuo browser per cancellare automaticamente o manualmente i cookie. \u00c8 anche possibile specificare che determinati cookie non possono essere piazzati. Un'altra opzione \u00e8 quella di modificare le impostazioni del tuo browser internet in modo da ricevere un messaggio ogni volta che viene inserito un cookie. Per ulteriori informazioni su queste opzioni, consultare le istruzioni nella sezione Guida del tuo browser.<\/p><p>Tieni presente che il nostro sito web potrebbe non funzionare correttamente se tutti i cookie sono disabilitati. Se cancelli i cookie nel vostro browser, essi verranno nuovamente inseriti dopo il consenso fornito quando visiterete nuovamente il nostro sito web.<\/p><h2>9. I tuoi diritti in relazione ai dati personali<\/h2><p>Hai i seguenti diritti relativi ai tuoi dati personali:<\/p><ul>\n                    <li>Hai il diritto di sapere quando i tuoi dati personali sono necessari, cosa succede ad essi, quanto a lungo verranno mantenuti.<\/li>\n                    <li>Diritto di accesso: hai il diritto ad accedere ai tuoi dati personali dei quali siamo a conoscenza.<\/li>\n                    <li>Diritto di rettifica: hai il diritto di completare, correggere, cancellare o bloccare i tuoi dati personali quando lo desideri.<\/li>\n                    <li>Se ci darai il consenso per elaborare i tuoi dati, hai il diritto di revocare questo consenso e di eliminare i tuoi dati personali.<\/li>\n                    <li>Diritto di trasferire i tuoi dati: hai il diritto di richiedere tutti i tuoi dati dal controllore e trasferirli tutti quanti ad un altro controllore.<\/li>\n                    <li>Diritto di opposizione: hai il diritto ad opporti al trattamento dei tuoi dati. Noi rispetteremo questa scelta, a meno che non ci siano delle motivazioni valide per trattarli.<\/li>\n                <\/ul><p>Per esercitare questi diritti, non esitate a contattarci. Si prega di fare riferimento ai dettagli di contatto in fondo a questa Cookie Policy. Se hai un reclamo su come gestiamo i tuoi dati, vorremmo sentirti, ma hai anche il diritto di presentare un reclamo all'autorit\u00e0 di vigilanza (l'Autorit\u00e0 per la Protezione dei Dati).<\/p><h2>10. Dettagli di contatto<\/h2><p>Per domande e\/o commenti riguardo la Cookie Policy e questa dichiarazione, per favore contattaci usando i seguenti dati di contatto:<\/p><p><span class=\"cmplz-contact-organisation\">Myrline SL<\/span><br>\n                      <span class=\"cmplz-contact-address\">C\/ PRUNERA 21 08415, BIGUES I RIELLS (BARCELONA), Barcelona \u2013 Espa\u00f1a.<\/span><br>\n                      <span class=\"cmplz-contact-country\">Spagna<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Sito web: <a href=\"https:\/\/www.laqcolours.com\/it\/\">https:\/\/www.laqcolours.com\/it\/<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">Email: <span class=\"cmplz-obfuscate\">m&#121;&#114;&#108;i&#110;&#101;@<span class=\"cmplz-fmail-domain\">&#101;x&#046;&#099;o&#109;<\/span>m&#121;&#114;&#108;&#105;n&#101;&#046;co&#109;<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Numero di telefono: 652 961 248<\/span><\/p><p>Questa politica sui cookie \u00e8 stata sincronizzata con <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> il Gennaio 21, 2022.<\/p><\/div>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;] Informativa sui cookie [\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1579","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.laqcolours.com\/it\/wp-json\/wp\/v2\/pages\/1579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laqcolours.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.laqcolours.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.laqcolours.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laqcolours.com\/it\/wp-json\/wp\/v2\/comments?post=1579"}],"version-history":[{"count":2,"href":"https:\/\/www.laqcolours.com\/it\/wp-json\/wp\/v2\/pages\/1579\/revisions"}],"predecessor-version":[{"id":1581,"href":"https:\/\/www.laqcolours.com\/it\/wp-json\/wp\/v2\/pages\/1579\/revisions\/1581"}],"wp:attachment":[{"href":"https:\/\/www.laqcolours.com\/it\/wp-json\/wp\/v2\/media?parent=1579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}